{"id":3279,"date":"2024-04-23T00:46:43","date_gmt":"2024-04-22T22:46:43","guid":{"rendered":"https:\/\/fbernadet.org\/?p=3279"},"modified":"2025-04-01T16:01:22","modified_gmt":"2025-04-01T14:01:22","slug":"articulo-sant-jordi-2024","status":"publish","type":"post","link":"https:\/\/fbernadet.org\/es\/articulo-sant-jordi-2024\/","title":{"rendered":"ART\u00cdCULO SANT JORDI 2024"},"content":{"rendered":"\n<p class=\"has-x-large-font-size\">ART\u00cdCULO SANT JORDI 2024<\/p>\n\n\n\n<p>\u00a1Otra vuelta al sol y Sant Jordi ya est\u00e1 aqu\u00ed!<\/p>\n\n\n\n<p>De buena ma\u00f1ana, nada m\u00e1s pisar la calle se nos dibuja una sonrisa, so\u00f1amos con los ojos abiertos, sintiendo el calor de uno de los d\u00edas m\u00e1s especiales del a\u00f1o. Nuestra fiesta m\u00e1s querida e internacional, un estallido de cultura pero tambi\u00e9n de romanticismo e ilusi\u00f3n. Un d\u00eda que nos transporta al momento en el que sent\u00edamos la magia y nada nos preocupaba.<\/p>\n\n\n\n<p>Un d\u00eda que nos transporta a la infancia, una etapa que deber\u00eda representar precisamente lo que es Sant Jordi: ilusi\u00f3n, esperanza, luz y color.<\/p>\n\n\n\n<p>La infancia es tambi\u00e9n una etapa fundamental en nuestras vidas, el momento en el que desarrollamos nuestro potencial y nuestra salud, tanto f\u00edsica como emocional. Una infancia sana, genera ciudadanos sanos y sociedades pr\u00f3speras. No hay mejor manera de construir futuro que el de proteger a todos los ni\u00f1os y ni\u00f1as de cualquier violencia, explotaci\u00f3n y abuso, sean cuales sean sus historias y circunstancias.<\/p>\n\n\n\n<p>\u00c9sta es la mayor responsabilidad que tenemos como adultos. Hoy puede ser un buen d\u00eda para recordarlo. Hoy que celebramos la vida, recordemos que la protecci\u00f3n de la infancia es un compromiso de todos y que el despertar de conciencias puede generar un gran cambio. Impliqu\u00e9monos en la transformaci\u00f3n que construir\u00e1 una sociedad m\u00e1s justa y libre de violencia. Construyamos entornos seguros, para disfrutar de una vida plena.<\/p>\n\n\n\n<p>Salgamos a la calle convencidos de que nunca es tarde para tener una infancia feliz, \u00e9ste es el motor que nos impulsa a todas las personas que trabajamos, colaboramos y ayudamos a la Fundaci\u00f3n Vicki Bernadet a seguir trabajando en la defensa de los derechos de la infancia. Hoy tambi\u00e9n es un buen d\u00eda para empezar a formar parte del <strong>Reto Com\u00fan<\/strong>.<\/p>\n\n\n\n<p>Peque\u00f1os gestos mejoran el mundo. Paseando entre paradas de libros y rosas, recordemos que Sant Jordi es tambi\u00e9n la fiesta de la cultura, un lenguaje universal, \u00edntimamente ligado a la lucha del tercer sector y punta de lanza del progreso, de la igualdad entre personas y del desarrollo social. Hoy tambi\u00e9n es un buen d\u00eda para disfrutar de la cultura que despierta conciencias y contribuir a la sensibilizaci\u00f3n y visualizaci\u00f3n que acerca realidades, genera empat\u00eda y nos empuja a participar en soluciones posibles.<\/p>\n\n\n\n<p>Rodeados de gente, miremos a los ojos de ni\u00f1os, ni\u00f1as y adolescentes y sintamos la fuerza para mover el mundo, para cambiarlo todo. En cada pueblo, en cada barrio, celebremos tambi\u00e9n la posibilidad de que cada d\u00eda sea Sant Jordi en las vidas de los m\u00e1s peque\u00f1os y peque\u00f1as.<\/p>\n\n\n\n<p>Hoy regalemos libros, rosas, amor y alegr\u00eda y no nos olvidemos de dibujar sonrisas. Regalemos protecci\u00f3n y cuidado. Regalemos presente y futuro. Y que Sant Jordi no acabe nunca.<\/p>\n\n\n\n<p>\u00a1Feliz Sant Jordi!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ART\u00cdCULO SANT JORDI 2024 \u00a1Otra vuelta al sol y Sant Jordi ya est\u00e1 aqu\u00ed! De buena ma\u00f1ana, nada m\u00e1s pisar la calle se nos dibuja una<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":5950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[279],"tags":[],"class_list":["post-3279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias_eventos"],"acf":[],"_links":{"self":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts\/3279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/comments?post=3279"}],"version-history":[{"count":0,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts\/3279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/media\/5950"}],"wp:attachment":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/media?parent=3279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/categories?post=3279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/tags?post=3279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}