{"id":1503,"date":"2020-11-19T22:06:49","date_gmt":"2020-11-19T21:06:49","guid":{"rendered":"http:\/\/fbernadet.org\/premis-lletra-magenta\/"},"modified":"2023-12-29T07:50:23","modified_gmt":"2023-12-29T06:50:23","slug":"premis-lletra-magenta","status":"publish","type":"post","link":"https:\/\/fbernadet.org\/es\/premis-lletra-magenta\/","title":{"rendered":"Premis Lletra Magenta"},"content":{"rendered":"<h3>Estamos muy contentas de compartir con todos vosotros la creaci\u00f3n de los Premios Literarios \u00abLletra Magenta\u00bb, fruto de la colaboraci\u00f3n conjunta de la Editorial Apostroph y la Fundaci\u00f3n Vicki Bernadet.<\/h3>\n<div><\/div>\n<div>Con el objetivo de promover un cambio social necesario, desde la Fundaci\u00f3n se apuesta por la cultura c\u00f3mo una herramienta de comunicaci\u00f3n inclusiva y transversal, \u00edntimamente ligada a la lucha social, punta de lanza del progreso, de la defensa de los derechos fundamentales y de la igualdad entre personas.<\/div>\n<div><\/div>\n<div>Apostroph es una editorial independiente. cuenta con dos l\u00edneas principales \u00abApostroph narrativa\u00bb y \u00abApostroph ensayo\u00bb. Su vocaci\u00f3n es la de editar y publicar libros de autoras y autores catalanes y espa\u00f1oles que escriben sobre nuestro tiempo con vocaci\u00f3n universal.<\/div>\n<div><\/div>\n<div>Juntos, unimos fuerzas, creando unos Premios Literarios anuales que reflejen la realidad de los abusos sexuales infantiles y ayuden en su sensibilizaci\u00f3n y prevenci\u00f3n.<\/div>\n<div><\/div>\n<div>Compartimos con vosotros el documento que recoge las bases de estos premios, invitando a difundir esta propuesta y a ser part\u00edcipes de este nuevo proyecto, comprometido con la lucha conjunta contra los abusos sexuales infantiles y con el apoyo al mundo de la literatura y a sus miembros, deseando sinceramente que sea de vuestro agrado.<\/div>\n<div><\/div>\n<div><a href=\"https:\/\/fbernadet.org\/desarrollo\/wp-content\/uploads\/2020\/11\/Premios-letra-magenta.pdf\">Premios letra magenta<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Estamos muy contentas de compartir con todos vosotros la creaci\u00f3n de los Premios Literarios \u00abLletra Magenta\u00bb, fruto de la colaboraci\u00f3n conjunta de la Editorial Apostroph y<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":1075,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[199],"tags":[],"class_list":["post-1503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidadsala-de-prensa"],"acf":[],"_links":{"self":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts\/1503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/comments?post=1503"}],"version-history":[{"count":0,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts\/1503\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/media\/1075"}],"wp:attachment":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/media?parent=1503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/categories?post=1503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/tags?post=1503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}