{"id":1499,"date":"2020-06-22T08:45:38","date_gmt":"2020-06-22T06:45:38","guid":{"rendered":"http:\/\/fbernadet.org\/9-recomendaciones-para-prevenir-el-abandono-de-la-terapia\/"},"modified":"2023-12-29T07:51:58","modified_gmt":"2023-12-29T06:51:58","slug":"9-recomendaciones-para-prevenir-el-abandono-de-la-terapia","status":"publish","type":"post","link":"https:\/\/fbernadet.org\/es\/9-recomendaciones-para-prevenir-el-abandono-de-la-terapia\/","title":{"rendered":"Nueve recomendaciones para prevenir el abandono de la terapia."},"content":{"rendered":"<h1>La adherencia a la terapia psicol\u00f3gica es clave para asegurar el bienestar de los pacientes.<\/h1>\n<p>Este a\u00f1o 2020 las trabajadoras de la Fundaci\u00f3n nos hemos fijado un objetivo com\u00fan: buscar formas de mejorar nuestro trabajo cada d\u00eda. Para nosotros es imprescindible ofrecer nuestros servicios con la m\u00e1xima calidad posible y nuestro compromiso en la prevenci\u00f3n y el abordaje del abuso sexual infantil a lo largo de 23 a\u00f1os as\u00ed lo demuestra. Sin embargo, nos sentimos en la obligaci\u00f3n de ir m\u00e1s all\u00e1: la experiencia no lo es todo, necesitamos tambi\u00e9n revisar seleccionados, preguntar a las usuarias e investigar con los datos que conocemos.<\/p>\n<p>Durante el \u00faltimo a\u00f1o el Servicio de Atenci\u00f3n ha trabajado conjuntamente con el Departamento de Formaci\u00f3n a fin de encontrar los puntos claves para promover la adherencia a la terapia de las usuarias de la fundaci\u00f3n. Tras analizar m\u00e1s de 750 casos y comprobar con orgullo que la Fundaci\u00f3n tiene las tasas de abandono de la terapia por debajo de la media encontrada en estudios internacionales, queremos compartir con todos vosotros las conclusiones de la investigaci\u00f3n.<\/p>\n<p>Esta investigaci\u00f3n ha sido posible gracias a la financiaci\u00f3n del Departamento de Trabajo, Asuntos Sociales y Familias de la Generalidad de Catalu\u00f1a, en el marco de la Cospe 2019. Tambi\u00e9n hemos contado con el asesoramiento de la Universidad de Barcelona con el fin de asegurar el m\u00e1ximo rigor cient\u00edfico.<\/p>\n<p>&nbsp;<\/p>\n<h2>\u00bfQuieres conocer algunas recomendaciones para prevenir el abandono de la terapia?<\/h2>\n<p>1. Ofrecer tratamiento psicol\u00f3gico gratuito.<\/p>\n<p>2. Trabajar con las familias y implicarlas en la terapia del ni\u00f1o o el adolescente.<\/p>\n<p>3. Trabajar las expectativas de los adolescentes sobre ritmo de la terapia.<\/p>\n<p>4. Vincular la paciente a la instituci\u00f3n.<\/p>\n<p>5. Formar a todo el personal sobre c\u00f3mo establecer un buen v\u00ednculo con los \/ las usuarias.<\/p>\n<p>6. Adaptarse a las necesidades de cada paciente de forma personalizada.<\/p>\n<p>7. Crear y proteger el v\u00ednculo terap\u00e9utico.<\/p>\n<p>8. Re-evaluar la calidad del v\u00ednculo a lo largo de la terapia.<\/p>\n<p>9. Ayudar a la persona a reconocer sus recursos personales.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14564 size-full\" src=\"https:\/\/fbernadet.org\/desarrollo\/wp-content\/uploads\/2020\/06\/Twitter-Cast@1.5x-100-scaled.jpg\" alt=\"\" width=\"771\" height=\"2560\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La adherencia a la terapia psicol\u00f3gica es clave para asegurar el bienestar de los pacientes. Este a\u00f1o 2020 las trabajadoras de la Fundaci\u00f3n nos hemos fijado<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[41],"tags":[],"class_list":["post-1499","post","type-post","status-publish","format-standard","hentry","category-sin-categorizar"],"acf":[],"_links":{"self":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts\/1499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/comments?post=1499"}],"version-history":[{"count":0,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts\/1499\/revisions"}],"wp:attachment":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/media?parent=1499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/categories?post=1499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/tags?post=1499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}