{"id":1477,"date":"2021-05-12T10:16:16","date_gmt":"2021-05-12T08:16:16","guid":{"rendered":"http:\/\/fbernadet.org\/cuentos-infantiles-para-prevenir-abuso-sexual-infantil-2\/"},"modified":"2023-12-29T07:49:30","modified_gmt":"2023-12-29T06:49:30","slug":"cuentos-infantiles-para-prevenir-abuso-sexual-infantil-2","status":"publish","type":"post","link":"https:\/\/fbernadet.org\/es\/cuentos-infantiles-para-prevenir-abuso-sexual-infantil-2\/","title":{"rendered":"Cuentos infantiles para prevenir el abuso sexual infantil"},"content":{"rendered":"<p>[vc_row][vc_column width=\u00bb2\/3&#8243;][vc_column_text]Empiezan las vacaciones escolares y el per\u00edodo de verano, un momento ideal para pasar tiempo en familia. Una de las muchas propuestas que se pueden hacer es compartir espacios de lectura de cuentos y libros. Por este motivo, desde la Fundaci\u00f3n Vicki Bernadet queremos ofreceros un peque\u00f1o listado de cuentos infantiles para abordar y hablar del abuso sexual infantil con vuestros hijos e hijas, y compartir con todos vosotros algunas reflexiones sobre el uso de los cuentos y orientaciones que faciliten la elecci\u00f3n del cuento m\u00e1s adecuado.[\/vc_column_text][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<h2>Antes de elegir un cuento infantil sobre abuso sexual infantil, ten en cuenta:<\/h2>\n<h3><strong>Un cuento o libro infantil es&#8230;<\/strong><\/h3>\n<ul>\n<li>Una herramienta \u00fatil para compartir y utilizar en el tiempo de ocio en familia.<\/li>\n<li>Una herramienta que facilita abordar un tema complejo, como el abuso sexual infantil, de manera sencilla. Los libros nos ayudan a empezar a hablar de diferentes temas y poner nombre a las cosas.<\/li>\n<li>Una herramienta que nos ayuda a dar pautas de comportamiento ante diversas situaciones.<\/li>\n<\/ul>\n<h3><strong>Un cuento o libro infantil NO es&#8230;<\/strong><\/h3>\n<ul>\n<li>Una herramienta de detecci\u00f3n del abuso sexual infantil o cualquier otra problem\u00e1tica. Si tienes sospechas de una posible situaci\u00f3n abusiva leer un cuento no es una buena opci\u00f3n, hay que buscar ayuda de alg\u00fan profesional y priorizar la protecci\u00f3n del ni\u00f1o o adolescente.<\/li>\n<li>Una gu\u00eda de actuaci\u00f3n ante una posible situaci\u00f3n de abuso.<\/li>\n<li>Un manual especializado ni un diccionario.<\/li>\n<\/ul>\n<h3>Criterios para escoger un cuento infantil que trate el abuso sexual infantil<\/h3>\n<p>A continuaci\u00f3n, tambi\u00e9n queremos compartir contigo el listado de criterios, que seg\u00fan nuestro punto de vista, debe poder tener cualquier libro que aborde el abuso sexual infantil. Con este listado queremos ayudarte a seleccionar los libros m\u00e1s adecuados entre las diferentes propuestas que puedes encontrar en el mercado editorial:<\/p>\n<ul>\n<li>El mensaje del cuento siempre debe ser positivo.<\/li>\n<li>El cuento no debe asustar ni en el mensaje ni en la imagen.<\/li>\n<li>El cuento nos facilitar\u00e1 poder hablar de una manera sencilla, amable y positiva de un tema complejo.<\/li>\n<li>Un buen cuento infantil debe hacer siempre una propuesta clara por una educaci\u00f3n afectivo sexual sana y en positivo.<\/li>\n<li>Los contenidos m\u00ednimos que debe abordar el cuento o libro infantil son: en una posible situaci\u00f3n de abuso hay que pedir siempre ayuda a personas adultas de confianza y no intentar resolver la situaci\u00f3n solo o sola, aprender a decir no, hay que explicar lo que no nos gusta, diferenciar entre secreto buenos y malos.<\/li>\n<\/ul>\n<p>Y finalmente, aqu\u00ed tienes una propuesta de cuentos infantiles dirigido a diferentes franjas de edad, desde los m\u00e1s peque\u00f1os hasta aquellos que se encuentran ya en la adolescencia. A la hora de seleccionar el cuento o libro infantil, recuerda tener presente la edad de tu hijo o hija y que la lectura compartida del cuento o libro infantil debe ser un momento tranquilo y de ocio familiar.<\/p>\n<p>\u00a1Buen verano y buenas lecturas![\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb9316&#8243; img_size=\u00bbmedium\u00bb alignment=\u00bbcenter\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_column_text]&#8217;Las Cortinas de Aire&#8217;, de la Fundaci\u00f3n Vicki Bernadet[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb9317&#8243; img_size=\u00bbmedium\u00bb alignment=\u00bbcenter\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_column_text]&#8217;Ni un besito a la fuerza&#8217; de Marion Mebes (Maite Canal Editora, 1994)[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb9313&#8243; img_size=\u00bbmedium\u00bb alignment=\u00bbcenter\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_column_text]&#8217;Azul, un cuento sobre el abuso&#8217; de Jos\u00e9 Andr\u00e9s Murillo y Marcela Paz (Thule Ediciones, 2017)[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb9320&#8243; img_size=\u00bbmedium\u00bb alignment=\u00bbcenter\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_column_text]&#8217;Ojos verdes&#8217; de Sara Arteaga y Luisa Fernanda (CEAPA, 2015)[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb9315&#8243; img_size=\u00bbmedium\u00bb alignment=\u00bbcenter\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_column_text]&#8217;\u00a1Estela, grita muy fuerte!&#8217; de Bel Olid y Martina Vanda (Fundaci\u00f3n Rana, 2008)[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb9318&#8243; img_size=\u00bbmedium\u00bb alignment=\u00bbcenter\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_column_text]&#8217;Noooooo. Una historia sobre abusos&#8217; de Kathryn Cole (Picarona, 2017)[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb9321&#8243; img_size=\u00bbmedium\u00bb alignment=\u00bbcenter\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_column_text]&#8217;\u00bfTienes un secreto?&#8217; de Jennifer Moore (El Ateneo, 2004)[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb9314&#8243; img_size=\u00bbmedium\u00bb alignment=\u00bbcenter\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_column_text]&#8217;El cuento de una rata mala&#8217; de Bryan Talbot (Astiberri, 2013)<\/p>\n<p>(a partir de 14 a\u00f1os)[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb9319&#8243; img_size=\u00bbmedium\u00bb alignment=\u00bbcenter\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_column_text]\u00bbPalabras envenedadas&#8217; de Maite Carranza (Edeb\u00e9, 2012)<\/p>\n<p>(a partir de 14 a\u00f1os)[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=\u00bb1\/3&#8243;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Empiezan las vacaciones escolares y el per\u00edodo de verano, un momento ideal para pasar tiempo en familia. Una de las muchas propuestas que se pueden hacer es compartir espacios de lectura de cuentos y libros. Por este motivo, desde la Fundaci\u00f3n Vicki Bernadet queremos ofreceros un peque\u00f1o listado de cuentos infantiles para abordar y hablar del abuso sexual infantil con vuestros hijos e hijas.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[166,147],"tags":[],"class_list":["post-1477","post","type-post","status-publish","format-standard","hentry","category-actualidadnoticias","category-blog"],"acf":[],"_links":{"self":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts\/1477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/comments?post=1477"}],"version-history":[{"count":0,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts\/1477\/revisions"}],"wp:attachment":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/media?parent=1477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/categories?post=1477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/tags?post=1477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}