{"id":1414,"date":"2016-12-02T09:57:57","date_gmt":"2016-12-02T08:57:57","guid":{"rendered":"http:\/\/fbernadet.org\/10-anos-de-la-convencion-de-los-derechos-de-las-personas-con-discapacidad-mucho-trabajo-por-hacer\/"},"modified":"2023-12-29T08:15:00","modified_gmt":"2023-12-29T07:15:00","slug":"10-anos-de-la-convencion-de-los-derechos-de-las-personas-con-discapacidad-mucho-trabajo-por-hacer","status":"publish","type":"post","link":"https:\/\/fbernadet.org\/es\/10-anos-de-la-convencion-de-los-derechos-de-las-personas-con-discapacidad-mucho-trabajo-por-hacer\/","title":{"rendered":"10 a\u00f1os de la Convenci\u00f3n de los derechos de las personas con discapacidad. \u00a1Mucho trabajo por hacer!"},"content":{"rendered":"<p style=\"text-align: justify;\">Celebrar aniversarios redondos a\u00a0menudo implica una revisi\u00f3n del trabajo realizado y de aquel que todav\u00eda queda pendiente. Tenemos deberes, es evidente, \u00a1y no pocos! No podemos, sin embargo, negar que ha habido avances muy importantes, un cambio de mentalidad en el derecho a decidir sobre la propia vida, en la modificaci\u00f3n de leyes que garantizan derechos b\u00e1sicos y fundamentales y, ponen a las personas con discapacidad en un primer plano, hasta ahora, a menudo negado.<\/p>\n<p style=\"text-align: justify;\">Este a\u00f1o, desde la Fundaci\u00f3n Vicki Bernadet hemos llevado a cabo diferentes tipos de acciones. Entre ellas nos gustar\u00eda destacar algunas que tienen un significado m\u00e1s\u00a0fuerte \u00a0y que esperamos que tengan un efecto positivo para ayudar al colectivo de gente con discapacidad a tener una vida m\u00e1s digna y de calidad.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/fbernadet.org\/desarrollo\/wp-content\/uploads\/2016\/09\/CartellinDISCutible1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4042\" title=\"CartellinDISCutible\" src=\"http:\/\/fbernadet.org\/desarrollo\/wp-content\/uploads\/2016\/09\/CartellinDISCutible1.jpg\" alt=\"\" width=\"1253\" height=\"1772\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Podemos finalmente tener una visi\u00f3n general de cu\u00e1l es la prevalencia de los diferentes maltratos gracias a la investigaci\u00f3n sobre las victimizaciones que afrontan las personas con DID y sus familias, llevada a cabo por Dincat, la Universidad de Barcelona y la propia Fundaci\u00f3n Vicki Bernadet. Esta investigaci\u00f3n nos muestra unos datos de prevalencia totalmente alarmantes, tanto a nivel de victimizaci\u00f3n general (donde 9 de cada 10 personas con DID ha sufrido una situaci\u00f3n de victimizaci\u00f3n a lo largo de su vida), como a abusos sexuales, (1 de cada 2 mujeres y 1 de cada 4 hombres es v\u00edctima de los mismos). Estas cifras, pues, permitir\u00e1n el desarrollo del arte. 16.1 de la Convenci\u00f3n dado que facilitar\u00e1n la adopci\u00f3n de medidas pertinentes en materia de protecci\u00f3n, tanto a nivel legislativo, administrativo, social, como educativo.<\/p>\n<p style=\"text-align: justify;\">La intervenci\u00f3n terap\u00e9utica especializada para personas con DID no s\u00f3lo para mejorar su calidad de vida sino tambi\u00e9n para reducir el alto riesgo de polivictimizaci\u00f3n que afecta al colectivo es esencial tal como se indica en el El art. 16.4. Desde la Fundaci\u00f3n hemos apostado por la Danza Movimiento Terapia (DMT) para ofrecer un recurso posibilitador a aquellas personas, que por razones principalmente cognitivas, no pueden acceder a terapias verbales. A\u00f1o tras a\u00f1o esperamos poder ir haciendo que el servicio llegue a m\u00e1s personas, dada la gran necesidad de atender al alto porcentaje de v\u00edctimas existente.<\/p>\n<p style=\"text-align: justify;\">A nivel de sensibilizaci\u00f3n destacamos dos iniciativas que hemos elaborado este a\u00f1o:<\/p>\n<p style=\"text-align: justify;\">&#8211; El v\u00eddeo pedag\u00f3gico <a title=\"Indiscutible\" href=\"http:\/\/www.indiscutible.cat\" target=\"_blank\" rel=\"noopener\">Indiscutible<\/a> que afronta el derecho de las personas con discapacidad a disfrutar de una sexualidad libre, plena y consentida. En \u00e9l se abordan tres tem\u00e1ticas: el derecho a decidir de las personas con discapacidad, los espacios y entornos de confianza y el abuso sexual y la credibilidad de las v\u00edctimas.<\/p>\n<p style=\"text-align: justify;\">&#8211; El p\u00f3ster \u00abParemos los malos tratos\u00bb (descargable a pie de p\u00e1gina) elaborado en el marco de una formaci\u00f3n realizada a personas con DID que viven aut\u00f3nomamente o con apoyo en el hogar y que cuenta con los magn\u00edficos dibujos de la Dolores Torrents, una de las participantes en el mismo.<\/p>\n<p style=\"text-align: justify;\">En total, hemos llevado a cabo acciones a trav\u00e9s de las cuales hemos podido ayudar a un total de 1.063 personas. \u00a1Esperamos que en 2017 nos permita seguir avanzando!<\/p>\n<p>Descarga p\u00f3ster <a title=\"No a los malos tratos\" href=\"http:\/\/fbernadet.org\/desarrollo\/wp-content\/uploads\/2016\/12\/poster-12.jpg\" target=\"_blank\" rel=\"noopener\">&#8216;Paremos los malos tratos&#8217;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Celebrar aniversarios redondos a\u00a0menudo implica una revisi\u00f3n del trabajo realizado y de aquel que todav\u00eda queda pendiente. Tenemos deberes, es evidente, \u00a1y no pocos! No podemos,<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[166,147],"tags":[],"class_list":["post-1414","post","type-post","status-publish","format-standard","hentry","category-actualidadnoticias","category-blog"],"acf":[],"_links":{"self":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts\/1414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/comments?post=1414"}],"version-history":[{"count":0,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts\/1414\/revisions"}],"wp:attachment":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/media?parent=1414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/categories?post=1414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/tags?post=1414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}