{"id":1411,"date":"2016-11-22T09:57:57","date_gmt":"2016-11-22T08:57:57","guid":{"rendered":"http:\/\/fbernadet.org\/entrega-de-la-medalla-de-honor-2016-a-la-fundacio-vicki-bernadet\/"},"modified":"2023-12-29T08:16:21","modified_gmt":"2023-12-29T07:16:21","slug":"entrega-de-la-medalla-de-honor-2016-a-la-fundacio-vicki-bernadet","status":"publish","type":"post","link":"https:\/\/fbernadet.org\/es\/entrega-de-la-medalla-de-honor-2016-a-la-fundacio-vicki-bernadet\/","title":{"rendered":"Entrega de la Medalla de Honor 2016 a la Fundaci\u00f3 Vicki Bernadet"},"content":{"rendered":"<p>Nos hace mucha ilusi\u00f3n hacer p\u00fablico que el Ayuntamiento de Barcelona otorgar\u00e1 esta tarde <a href=\"http:\/\/ajuntament.barcelona.cat\/premsa\/2016\/10\/28\/barcelona-aprova-les-medalles-dhonor-del-2016\/\" target=\"_blank\" rel=\"noopener\">Medalla de Honor<\/a> 2016 a la Fundaci\u00f3n Vicki Bernadet.<\/p>\n<p><a href=\"http:\/\/fbernadet.org\/desarrollo\/wp-content\/uploads\/2016\/11\/Medalla_dHonor.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4304\" title=\"Medalla_dHonor\" src=\"http:\/\/fbernadet.org\/desarrollo\/wp-content\/uploads\/2016\/11\/Medalla_dHonor.jpg\" alt=\"\" width=\"300\" height=\"233\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">En palabras del Teniente de Alcalde Gerard Pisarello<em> \u00abel Ayuntamiento quiere hacer un reconocimiento a algunas de estas personas y entidades que han destacado en sus campos respectivos y que con su esfuerzo y su ilusi\u00f3n contribuyen, d\u00eda a d\u00eda, a reivindicar una ciudad mejor para los barceloneses y las barcelonesas. Sus ejemplos contribuyen a la realizaci\u00f3n personal y colectiva y nos ayudan a avanzar en el camino de la cohesi\u00f3n social y el compromiso ciudadano \u00ab.<\/em><\/p>\n<p>Con estas medallas, el Ayuntamiento reconoce a 25 personas y entidades que han contribuido al desarrollo de una conciencia ciudadana y c\u00edvica, as\u00ed como de sus valores y virtudes. La ciudad rinde homenaje al empuje y generosidad de la sociedad civil.<\/p>\n<p style=\"text-align: justify;\">Un premio como la Medalla de Honor servir\u00e1 para hacer m\u00e1s visible a la sociedad la problem\u00e1tica de los abusos sexuales en la infancia, un tema que llevamos trabajando desde hace 20 a\u00f1os en la Fundaci\u00f3n Vicki Bernadet, y a pesar de que somos conscientes de que nos queda mucho camino por recorrer, tambi\u00e9n celebramos los avances logrados en esta materia.<\/p>\n<p style=\"text-align: justify;\">Queremos transmitir tambi\u00e9n nuestra alegr\u00eda y gratitud\u00a0 a todos los profesionales que nos han acompa\u00f1ado en este per\u00edodo, as\u00ed como a las entidades y particulares que nos han apoyado de muchas maneras durante este tiempo para llevar a cabo nuestra labor de protecci\u00f3n a la infancia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos hace mucha ilusi\u00f3n hacer p\u00fablico que el Ayuntamiento de Barcelona otorgar\u00e1 esta tarde Medalla de Honor 2016 a la Fundaci\u00f3n Vicki Bernadet. En palabras del<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[166,147],"tags":[],"class_list":["post-1411","post","type-post","status-publish","format-standard","hentry","category-actualidadnoticias","category-blog"],"acf":[],"_links":{"self":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts\/1411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/comments?post=1411"}],"version-history":[{"count":0,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts\/1411\/revisions"}],"wp:attachment":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/media?parent=1411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/categories?post=1411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/tags?post=1411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}