{"id":1367,"date":"2015-06-11T09:57:45","date_gmt":"2015-06-11T07:57:45","guid":{"rendered":"http:\/\/fbernadet.org\/cierre-grupo-terapeutico-2015\/"},"modified":"2023-12-29T08:34:27","modified_gmt":"2023-12-29T07:34:27","slug":"cierre-grupo-terapeutico-2015","status":"publish","type":"post","link":"https:\/\/fbernadet.org\/es\/cierre-grupo-terapeutico-2015\/","title":{"rendered":"Cierre Grupo Terap\u00e9utico 2015"},"content":{"rendered":"<p>Este mes nos hemos despedido del grupo terap\u00e9utico 2015 dirigido a personas adultas v\u00edctimas de abusos sexuales en su infancia y\/o adolescencia que se inici\u00f3 el pasado mes de febrero. En esta ocasi\u00f3n han participado nueve personas y nos ha acompa\u00f1ado una estudiante de pr\u00e1cticas de psicolog\u00eda de la UAB.<\/p>\n<p>Durante estos cuatro meses se han trabajado diferentes temas relacionados con las consecuencias de los ASI, tales como: la autoestima, la confianza, las relaciones de pareja, las relaciones familiares y la sexualidad.<\/p>\n<p>La Presidenta de la entidad, Vicki Bernadet asisti\u00f3 a la \u00faltima sesi\u00f3n de clausura, invitando a los participantes a poder continuar vinculados a la entidad a trav\u00e9s de proyectos de sensibilizaci\u00f3n y difusi\u00f3n.<\/p>\n<p>Los miembros del grupo compart\u00edan que las sesiones les han dado la posibilidad de poder hablar de lo que vivieron en un entorno de confianza y respeto que han valorado positivamente. Esperamos que su experiencia ayude a mucha m\u00e1s gente a romper el silencio.<\/p>\n<div id=\"attachment_3113\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/fbernadet.org\/comiatgt2015\/grupo-de-ayuda-mutua\/\" rel=\"attachment wp-att-3113\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3113\" class=\" wp-image-3113 \" title=\"Grupo de Ayuda M\u00fatua\" src=\"https:\/\/fbernadet.org\/desarrollo\/wp-content\/uploads\/2015\/06\/Grupo-de-Ayuda-Mu%cc%81tua.gif\" alt=\"\" width=\"622\" height=\"406\" \/><\/a><p id=\"caption-attachment-3113\" class=\"wp-caption-text\">Fotograf\u00eda Ana Jim\u00e9nez \u2013 copyright<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este mes nos hemos despedido del grupo terap\u00e9utico 2015 dirigido a personas adultas v\u00edctimas de abusos sexuales en su infancia y\/o adolescencia que se inici\u00f3 el<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[166,147],"tags":[],"class_list":["post-1367","post","type-post","status-publish","format-standard","hentry","category-actualidadnoticias","category-blog"],"acf":[],"_links":{"self":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts\/1367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/comments?post=1367"}],"version-history":[{"count":0,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts\/1367\/revisions"}],"wp:attachment":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/media?parent=1367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/categories?post=1367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/tags?post=1367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}