{"id":1304,"date":"2016-05-31T09:57:33","date_gmt":"2016-05-31T07:57:33","guid":{"rendered":"http:\/\/fbernadet.org\/donacion-las-cinco\/"},"modified":"2023-12-29T08:23:43","modified_gmt":"2023-12-29T07:23:43","slug":"donacion-las-cinco","status":"publish","type":"post","link":"https:\/\/fbernadet.org\/es\/donacion-las-cinco\/","title":{"rendered":"Donaci\u00f3n &#8216;Las Cinco&#8217;"},"content":{"rendered":"<p>El pasado jueves 24 marzo el grupo Las Cinco celebr\u00f3 una de sus fiestas en la sala Razzmatazz de Barcelona. El colectivo de las Cinco es el resultado de la uni\u00f3n de las fiestas: SomosLas, popa, La Ka, La Rebujito y Churros con Chocolate, que se dedican desde hace diez a\u00f1os a organizar fiestas y se unen peri\u00f3dicamente para montar una de bien grande y sacudi\u00f3 la Ciudad Condal con su m\u00fasica y espect\u00e1culo. Queremos agradecer su compromiso ya que destinaron los beneficios de esta fiesta en nuestra causa.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/fbernadet.org\/es\/la-fundacion\/quien-somos\/\" rel=\"attachment wp-att-3538\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3538\" title=\"Gracias-Lascinco\" src=\"http:\/\/fbernadet.org\/desarrollo\/wp-content\/uploads\/2016\/05\/Gracias-Lascinco.jpg\" alt=\"\" width=\"476\" height=\"390\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado jueves 24 marzo el grupo Las Cinco celebr\u00f3 una de sus fiestas en la sala Razzmatazz de Barcelona. El colectivo de las Cinco es<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[166,147],"tags":[],"class_list":["post-1304","post","type-post","status-publish","format-standard","hentry","category-actualidadnoticias","category-blog"],"acf":[],"_links":{"self":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts\/1304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/comments?post=1304"}],"version-history":[{"count":0,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/posts\/1304\/revisions"}],"wp:attachment":[{"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/media?parent=1304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/categories?post=1304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fbernadet.org\/es\/wp-json\/wp\/v2\/tags?post=1304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}